{"id":402,"count":60,"description":"Het Midden-Oosten en Afrika zijn dynamische regio\u2019s met jonge bevolkingen, complexe structuren en veel veerkracht en innovatie. We ondersteunen mensen en organisaties in deze regio\u2019s bij het navigeren door die complexiteit. Voorbeelden van ons werk in het Midden-Oosten en Afrika vind je hieronder.","link":"https:\/\/perspectivity.org\/nl\/tag\/midden-oosten-afrika\/","name":"Midden-Oosten &amp; Afrika","slug":"midden-oosten-afrika","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/perspectivity.org\/nl\/wp-json\/wp\/v2\/tags\/402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perspectivity.org\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/perspectivity.org\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/perspectivity.org\/nl\/wp-json\/wp\/v2\/posts?tags=402"},{"href":"https:\/\/perspectivity.org\/nl\/wp-json\/wp\/v2\/tribe_events?tags=402"},{"href":"https:\/\/perspectivity.org\/nl\/wp-json\/wp\/v2\/tec_calendar_embed?tags=402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}